{"id":20325,"date":"2017-05-31T16:28:35","date_gmt":"2017-05-31T14:28:35","guid":{"rendered":"https:\/\/barenboim-said.org\/?p=20325"},"modified":"2026-06-26T11:46:54","modified_gmt":"2026-06-26T09:46:54","slug":"campamento-iniciacion-la-musica-2017","status":"publish","type":"post","link":"https:\/\/barenboim-said.org\/en\/educacion-musical-en-andalucia\/campamento-iniciacion-la-musica-2017\/","title":{"rendered":"Campamento de Iniciaci\u00f3n a la M\u00fasica 2017"},"content":{"rendered":"<p><span style=\"color: #00ccff;\"><strong><a style=\"color: #00ccff;\" href=\"https:\/\/barenboim-said.org\/inscripcion-campamento-2017\/\">YA SE HAN AGOTADO LAS PLAZAS PARA EL CAMPAMENTO DE INICIACI\u00d3N A LA M\u00daSICA. PUEDE INSCRIBIR A SUS HIJOS\/AS EN LA LISTA DE RESERVA A TRAV\u00c9S DE ESTE ENLACE.\u00a0<\/a><\/strong><\/span><\/p>\n<p>La Fundaci\u00f3n Barenboim-Said organiza un\u00a0<strong>Campamento de Iniciaci\u00f3n a la M\u00fasica en Sevilla<\/strong>\u00a0durante los primeros d\u00edas de las vacaciones escolares de verano. Este curso, de dos semanas de duraci\u00f3n, se desarrollar\u00e1\u00a0<strong>del 26 de junio al 7 de julio\u00a0de lunes a viernes en el CEIP Juan Sebasti\u00e1n Elcano de Sevilla<\/strong> (C\/Lyon, s\/n Los Bermejales), gracias a la colaboraci\u00f3n de este centro educativo y del Conservatorio Elemental de M\u00fasica La Palmera.<\/p>\n<p>En este Campamento de Iniciaci\u00f3n a la M\u00fasica\u00a0<strong>pueden\u00a0participar escolares nacidos entre los a\u00f1os 2007 y 2012<\/strong>. Para inscribirse <strong>no es necesario tener formaci\u00f3n musical previa<\/strong>, ya que durante el curso el profesorado de la Fundaci\u00f3n imparte de una manera l\u00fadica y enfocada a las edades de los asistentes nociones elementales de educaci\u00f3n musical y conocimientos b\u00e1sicos de la t\u00e9cnica instrumental del <strong>piano, el viol\u00edn y la percusi\u00f3n, as\u00ed como de canto<\/strong>.<\/p>\n<p>Adem\u00e1s de la formaci\u00f3n puramente instrumental, los ni\u00f1os y ni\u00f1as participar\u00e1n en <strong>diversos talleres musicales<\/strong> como construcci\u00f3n de instrumentos musicales, improvisaci\u00f3n y creatividad, batucada o interpretaci\u00f3n musical de obras maestras de la pintura. Asimismo, al finalizar el campamento ofrecer\u00e1n una actuaci\u00f3n musical como muestra del trabajo desarrollado durante el mismo.<\/p>\n<p>El Campamento ser\u00e1 <strong>impartido por docentes especialistas en educaci\u00f3n musical infantil<\/strong> de la Fundaci\u00f3n Barenboim-Said en horario de 9:30 a 14:00. Con esta iniciativa la Fundaci\u00f3n pretende tambi\u00e9n contribuir a la conciliaci\u00f3n familiar y laboral. Por ello, existe un aula matinal gratuita de 8:30 a 9:30 horas y la recogida se realiza entre las 14:00 y las 14:30 horas.<\/p>\n<p>El precio de la matr\u00edcula es de 100 \u20ac por participante, si bien la Fundaci\u00f3n ofrece bonificaciones del 100% de la matr\u00edcula a familias con ambos progenitores o monoparentales que acrediten situaci\u00f3n de desempleo, as\u00ed como un descuento del 15% para hermanos\/as en ambas matr\u00edculas.<\/p>\n<p><span style=\"color: #00ccff;\"><a style=\"color: #00ccff;\" href=\"https:\/\/barenboim-said.org\/inscripcion-campamento-2017\/\"><strong>Las inscripciones estar\u00e1n disponibles pinchando aqu\u00ed a partir del 1 de junio a las 10:00 h<\/strong>.<\/a><\/span> Debido al n\u00famero limitado de plazas, el alumnado ser\u00e1 admitido por estricto orden de recepci\u00f3n de las inscripciones.<\/p>\n<p>M\u00e1s informaci\u00f3n: 955\u00a003 73 85 \/ raquel.g.sanchez@juntadeandalucia.es<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-20357\" src=\"https:\/\/barenboim-said.org\/wp-content\/uploads\/2017\/05\/Campamento-iniciacion-a-la-musica-1-212x300.jpg\" alt=\"Campamento-iniciacion-a-la-musica\" width=\"212\" height=\"300\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>YA SE HAN AGOTADO LAS PLAZAS PARA EL CAMPAMENTO DE INICIACI\u00d3N A LA M\u00daSICA. PUEDE INSCRIBIR A SUS HIJOS\/AS EN LA LISTA DE RESERVA A TRAV\u00c9S DE ESTE ENLACE.\u00a0 La Fundaci\u00f3n Barenboim-Said organiza un\u00a0Campamento de Iniciaci\u00f3n a la M\u00fasica en Sevilla\u00a0durante los primeros d\u00edas de las vacaciones escolares de verano. Este curso, de dos semanas [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":20329,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[225],"tags":[],"class_list":["post-20325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion-musical-en-andalucia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campamento de Iniciaci\u00f3n a la M\u00fasica 2017 - Fundaci\u00f3n Barenboim-Said<\/title>\n<meta name=\"description\" content=\"El Campamento de Iniciaci\u00f3n a la M\u00fasica Barenboim-Said 2017 se celebra del 26 de junio al 7 de julio en el CEIP Juan Sebasti\u00e1n Elcano de Sevilla.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/barenboim-said.org\/en\/educacion-musical-en-andalucia\/campamento-iniciacion-la-musica-2017\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campamento de Iniciaci\u00f3n a la M\u00fasica 2017 - Fundaci\u00f3n Barenboim-Said\" \/>\n<meta property=\"og:description\" content=\"El Campamento de Iniciaci\u00f3n a la M\u00fasica Barenboim-Said 2017 se celebra del 26 de junio al 7 de julio en el CEIP Juan Sebasti\u00e1n Elcano de Sevilla.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/barenboim-said.org\/en\/educacion-musical-en-andalucia\/campamento-iniciacion-la-musica-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Barenboim-Said\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-31T14:28:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-26T09:46:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/barenboim-said.org\/wp-content\/uploads\/2017\/05\/campamento_crop.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"BS_Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"BS_Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/barenboim-said.org\\\/en\\\/educacion-musical-en-andalucia\\\/campamento-iniciacion-la-musica-2017\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/barenboim-said.org\\\/en\\\/educacion-musical-en-andalucia\\\/campamento-iniciacion-la-musica-2017\\\/\"},\"author\":{\"name\":\"BS_Admin\",\"@id\":\"https:\\\/\\\/barenboim-said.org\\\/en\\\/#\\\/schema\\\/person\\\/31517d12b71452466a84c5b2390457d3\"},\"headline\":\"Campamento de Iniciaci\u00f3n a la M\u00fasica 2017\",\"datePublished\":\"2017-05-31T14:28:35+00:00\",\"dateModified\":\"2026-06-26T09:46:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/barenboim-said.org\\\/en\\\/educacion-musical-en-andalucia\\\/campamento-iniciacion-la-musica-2017\\\/\"},\"wordCount\":412,\"image\":{\"@id\":\"https:\\\/\\\/barenboim-said.org\\\/en\\\/educacion-musical-en-andalucia\\\/campamento-iniciacion-la-musica-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/barenboim-said.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/campamento_crop.jpg\",\"articleSection\":[\"Educaci\u00f3n Musical en Andaluc\u00eda\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/barenboim-said.org\\\/en\\\/educacion-musical-en-andalucia\\\/campamento-iniciacion-la-musica-2017\\\/\",\"url\":\"https:\\\/\\\/barenboim-said.org\\\/en\\\/educacion-musical-en-andalucia\\\/campamento-iniciacion-la-musica-2017\\\/\",\"name\":\"Campamento de Iniciaci\u00f3n a la M\u00fasica 2017 - Fundaci\u00f3n Barenboim-Said\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/barenboim-said.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/barenboim-said.org\\\/en\\\/educacion-musical-en-andalucia\\\/campamento-iniciacion-la-musica-2017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/barenboim-said.org\\\/en\\\/educacion-musical-en-andalucia\\\/campamento-iniciacion-la-musica-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/barenboim-said.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/campamento_crop.jpg\",\"datePublished\":\"2017-05-31T14:28:35+00:00\",\"dateModified\":\"2026-06-26T09:46:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/barenboim-said.org\\\/en\\\/#\\\/schema\\\/person\\\/31517d12b71452466a84c5b2390457d3\"},\"description\":\"El Campamento de Iniciaci\u00f3n a la M\u00fasica Barenboim-Said 2017 se celebra del 26 de junio al 7 de julio en el CEIP Juan Sebasti\u00e1n Elcano de Sevilla.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/barenboim-said.org\\\/en\\\/educacion-musical-en-andalucia\\\/campamento-iniciacion-la-musica-2017\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/barenboim-said.org\\\/en\\\/educacion-musical-en-andalucia\\\/campamento-iniciacion-la-musica-2017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/barenboim-said.org\\\/en\\\/educacion-musical-en-andalucia\\\/campamento-iniciacion-la-musica-2017\\\/#primaryimage\",\"url\":\"https:\\\/\\\/barenboim-said.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/campamento_crop.jpg\",\"contentUrl\":\"https:\\\/\\\/barenboim-said.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/campamento_crop.jpg\",\"width\":1140,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/barenboim-said.org\\\/en\\\/educacion-musical-en-andalucia\\\/campamento-iniciacion-la-musica-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"INICIO\",\"item\":\"https:\\\/\\\/barenboim-said.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campamento de Iniciaci\u00f3n a la M\u00fasica 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/barenboim-said.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/barenboim-said.org\\\/en\\\/\",\"name\":\"Fundaci\u00f3n Barenboim-Said\",\"description\":\"Formamos a los m\u00fasicos del futuro\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/barenboim-said.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/barenboim-said.org\\\/en\\\/#\\\/schema\\\/person\\\/31517d12b71452466a84c5b2390457d3\",\"name\":\"BS_Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/15561b81f8cacd98bd60f0e04f3e0fd2e0df8352c68a65147e522c48230550ac?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/15561b81f8cacd98bd60f0e04f3e0fd2e0df8352c68a65147e522c48230550ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/15561b81f8cacd98bd60f0e04f3e0fd2e0df8352c68a65147e522c48230550ac?s=96&d=mm&r=g\",\"caption\":\"BS_Admin\"},\"url\":\"https:\\\/\\\/barenboim-said.org\\\/en\\\/author\\\/bs_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campamento de Iniciaci\u00f3n a la M\u00fasica 2017 - Fundaci\u00f3n Barenboim-Said","description":"El Campamento de Iniciaci\u00f3n a la M\u00fasica Barenboim-Said 2017 se celebra del 26 de junio al 7 de julio en el CEIP Juan Sebasti\u00e1n Elcano de Sevilla.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/barenboim-said.org\/en\/educacion-musical-en-andalucia\/campamento-iniciacion-la-musica-2017\/","og_locale":"en_US","og_type":"article","og_title":"Campamento de Iniciaci\u00f3n a la M\u00fasica 2017 - Fundaci\u00f3n Barenboim-Said","og_description":"El Campamento de Iniciaci\u00f3n a la M\u00fasica Barenboim-Said 2017 se celebra del 26 de junio al 7 de julio en el CEIP Juan Sebasti\u00e1n Elcano de Sevilla.","og_url":"https:\/\/barenboim-said.org\/en\/educacion-musical-en-andalucia\/campamento-iniciacion-la-musica-2017\/","og_site_name":"Fundaci\u00f3n Barenboim-Said","article_published_time":"2017-05-31T14:28:35+00:00","article_modified_time":"2026-06-26T09:46:54+00:00","og_image":[{"width":1140,"height":600,"url":"https:\/\/barenboim-said.org\/wp-content\/uploads\/2017\/05\/campamento_crop.jpg","type":"image\/jpeg"}],"author":"BS_Admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"BS_Admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/barenboim-said.org\/en\/educacion-musical-en-andalucia\/campamento-iniciacion-la-musica-2017\/#article","isPartOf":{"@id":"https:\/\/barenboim-said.org\/en\/educacion-musical-en-andalucia\/campamento-iniciacion-la-musica-2017\/"},"author":{"name":"BS_Admin","@id":"https:\/\/barenboim-said.org\/en\/#\/schema\/person\/31517d12b71452466a84c5b2390457d3"},"headline":"Campamento de Iniciaci\u00f3n a la M\u00fasica 2017","datePublished":"2017-05-31T14:28:35+00:00","dateModified":"2026-06-26T09:46:54+00:00","mainEntityOfPage":{"@id":"https:\/\/barenboim-said.org\/en\/educacion-musical-en-andalucia\/campamento-iniciacion-la-musica-2017\/"},"wordCount":412,"image":{"@id":"https:\/\/barenboim-said.org\/en\/educacion-musical-en-andalucia\/campamento-iniciacion-la-musica-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/barenboim-said.org\/wp-content\/uploads\/2017\/05\/campamento_crop.jpg","articleSection":["Educaci\u00f3n Musical en Andaluc\u00eda"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/barenboim-said.org\/en\/educacion-musical-en-andalucia\/campamento-iniciacion-la-musica-2017\/","url":"https:\/\/barenboim-said.org\/en\/educacion-musical-en-andalucia\/campamento-iniciacion-la-musica-2017\/","name":"Campamento de Iniciaci\u00f3n a la M\u00fasica 2017 - Fundaci\u00f3n Barenboim-Said","isPartOf":{"@id":"https:\/\/barenboim-said.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/barenboim-said.org\/en\/educacion-musical-en-andalucia\/campamento-iniciacion-la-musica-2017\/#primaryimage"},"image":{"@id":"https:\/\/barenboim-said.org\/en\/educacion-musical-en-andalucia\/campamento-iniciacion-la-musica-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/barenboim-said.org\/wp-content\/uploads\/2017\/05\/campamento_crop.jpg","datePublished":"2017-05-31T14:28:35+00:00","dateModified":"2026-06-26T09:46:54+00:00","author":{"@id":"https:\/\/barenboim-said.org\/en\/#\/schema\/person\/31517d12b71452466a84c5b2390457d3"},"description":"El Campamento de Iniciaci\u00f3n a la M\u00fasica Barenboim-Said 2017 se celebra del 26 de junio al 7 de julio en el CEIP Juan Sebasti\u00e1n Elcano de Sevilla.","breadcrumb":{"@id":"https:\/\/barenboim-said.org\/en\/educacion-musical-en-andalucia\/campamento-iniciacion-la-musica-2017\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/barenboim-said.org\/en\/educacion-musical-en-andalucia\/campamento-iniciacion-la-musica-2017\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/barenboim-said.org\/en\/educacion-musical-en-andalucia\/campamento-iniciacion-la-musica-2017\/#primaryimage","url":"https:\/\/barenboim-said.org\/wp-content\/uploads\/2017\/05\/campamento_crop.jpg","contentUrl":"https:\/\/barenboim-said.org\/wp-content\/uploads\/2017\/05\/campamento_crop.jpg","width":1140,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/barenboim-said.org\/en\/educacion-musical-en-andalucia\/campamento-iniciacion-la-musica-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"INICIO","item":"https:\/\/barenboim-said.org\/en\/"},{"@type":"ListItem","position":2,"name":"Campamento de Iniciaci\u00f3n a la M\u00fasica 2017"}]},{"@type":"WebSite","@id":"https:\/\/barenboim-said.org\/en\/#website","url":"https:\/\/barenboim-said.org\/en\/","name":"Fundaci\u00f3n Barenboim-Said","description":"Formamos a los m\u00fasicos del futuro","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/barenboim-said.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/barenboim-said.org\/en\/#\/schema\/person\/31517d12b71452466a84c5b2390457d3","name":"BS_Admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/15561b81f8cacd98bd60f0e04f3e0fd2e0df8352c68a65147e522c48230550ac?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/15561b81f8cacd98bd60f0e04f3e0fd2e0df8352c68a65147e522c48230550ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/15561b81f8cacd98bd60f0e04f3e0fd2e0df8352c68a65147e522c48230550ac?s=96&d=mm&r=g","caption":"BS_Admin"},"url":"https:\/\/barenboim-said.org\/en\/author\/bs_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/barenboim-said.org\/en\/wp-json\/wp\/v2\/posts\/20325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/barenboim-said.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/barenboim-said.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/barenboim-said.org\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/barenboim-said.org\/en\/wp-json\/wp\/v2\/comments?post=20325"}],"version-history":[{"count":1,"href":"https:\/\/barenboim-said.org\/en\/wp-json\/wp\/v2\/posts\/20325\/revisions"}],"predecessor-version":[{"id":44964,"href":"https:\/\/barenboim-said.org\/en\/wp-json\/wp\/v2\/posts\/20325\/revisions\/44964"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/barenboim-said.org\/en\/wp-json\/wp\/v2\/media\/20329"}],"wp:attachment":[{"href":"https:\/\/barenboim-said.org\/en\/wp-json\/wp\/v2\/media?parent=20325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/barenboim-said.org\/en\/wp-json\/wp\/v2\/categories?post=20325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/barenboim-said.org\/en\/wp-json\/wp\/v2\/tags?post=20325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}